{"id":567,"date":"2022-05-18T10:27:15","date_gmt":"2022-05-18T13:27:15","guid":{"rendered":"https:\/\/www.agenciaexplorer.com.br\/?p=567"},"modified":"2023-12-14T13:37:16","modified_gmt":"2023-12-14T16:37:16","slug":"novidades-do-google-ads-analytics-e-google-meu-negocio","status":"publish","type":"post","link":"https:\/\/agenciaexplorer.com.br\/blog\/artigo\/novidades-do-google-ads-analytics-e-google-meu-negocio\/","title":{"rendered":"Novidades do Google Ads, Analytics e Google Meu Neg\u00f3cio"},"content":{"rendered":"<p>O m\u00eas de maio ainda n\u00e3o terminou, entretanto, j\u00e1 est\u00e1 marcado por diversas pequenas novidades e melhorias que o Google est\u00e1 aplicando em suas plataformas.<!--more--><\/p>\n<p><strong>Google Ads<\/strong><\/p>\n<p>Na ferramenta de an\u00fancios, o Google apresentou a nova campanha de <strong>m\u00e1xima performance<\/strong> (PMax) para o <strong>Google Shopping<\/strong>.<\/p>\n<p>Vale destacar que o recurso havia sido lan\u00e7ado em 2020, por\u00e9m, teve pouca ades\u00e3o por parte dos anunciantes.<\/p>\n<p>Para estimular a utiliza\u00e7\u00e3o, o Google &#8211; al\u00e9m de prometer mais efici\u00eancia e desempenho nas campanha &#8211; disponibilizou um bot\u00e3o simples que permite migrar campanhas em antigos formatos a partir de um \u00fanico clique.<\/p>\n<p>Abaixo os principais benef\u00edcios da nova campanha:<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-569\" src=\"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/themes\/maktub\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/www.agenciaexplorer.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34.jpeg\" alt=\"\" width=\"502\" height=\"308\" title=\"\" data-srcset=\"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34.jpeg 629w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-300x184.jpeg 300w\" data-sizes=\"auto, (max-width: 502px) 100vw, 502px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Ainda no Ads, o Google anunciou que a partir de 30\/06, n\u00e3o ser\u00e1 mais poss\u00edvel criar ou editar <strong>an\u00fancios de texto expandido<\/strong>.<\/p>\n<p>A partir dessa data, os <strong>an\u00fancios responsivos de pesquisas<\/strong> ser\u00e3o 100% obrigat\u00f3rios.<\/p>\n<p>Outro ponto importante \u00e9 que o Google modernizou os an\u00fancios responsivos, permitindo mais espa\u00e7o para transmitir a mensagem: adi\u00e7\u00e3o de um terceiro t\u00edtulo, adi\u00e7\u00e3o de uma segunda descri\u00e7\u00e3o e usar at\u00e9 90 caracteres para cada descri\u00e7\u00e3o.<\/p>\n<p>Nota: Aqui na Explorer, j\u00e1 trabalhamos preventivamente na migra\u00e7\u00e3o de todos os an\u00fancios legados de texto expandido. Dessa forma, nenhum cliente ter\u00e1 impacto.<\/p>\n<p><strong>Google Analytics<\/strong><\/p>\n<p>O recurso de tempo real do <strong>Google Analytics<\/strong> recebeu uma discreta atualiza\u00e7\u00e3o, por\u00e9m, que deixou muita gente perdida.<\/p>\n<p>A se\u00e7\u00e3o de <strong>tempo real<\/strong> agora apresenta os resultados dos \u00faltimos 5 minutos, n\u00e3o mais os 30 minutos anteriores.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-570\" src=\"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/themes\/maktub\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/www.agenciaexplorer.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-1.jpeg\" alt=\"\" width=\"647\" height=\"219\" title=\"\" data-srcset=\"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-1.jpeg 1280w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-1-300x101.jpeg 300w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-1-1024x346.jpeg 1024w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-1-768x260.jpeg 768w\" data-sizes=\"auto, (max-width: 647px) 100vw, 647px\" \/><\/p>\n<p>&nbsp;<\/p>\n<p>Como a mudan\u00e7a foi bastante sutil (no canto superior \u00e0 direita da imagem acima \u00e9 poss\u00edvel ver a informa\u00e7\u00e3o de usu\u00e1rios ativos nos \u00faltimos <strong>5 minutos<\/strong>) e sem comunica\u00e7\u00e3o em grande escala, realmente pegou muita gente de surpresa.<\/p>\n<p><strong>Google Meu Neg\u00f3cio<\/strong><\/p>\n<p>Para fechar as atualiza\u00e7\u00f5es, o Google tamb\u00e9m confirmou a <strong>descontinuidade do Google Meu Neg\u00f3cio<\/strong>. A plataforma era respons\u00e1vel por centralizar a gest\u00e3o das listagens do Google Maps.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter wp-image-571\" src=\"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/themes\/maktub\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/www.agenciaexplorer.com.br\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-2.jpeg\" alt=\"\" width=\"537\" height=\"424\" title=\"\" data-srcset=\"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-2.jpeg 1267w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-2-300x237.jpeg 300w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-2-1024x808.jpeg 1024w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/WhatsApp-Image-2022-05-18-at-10.11.34-2-768x606.jpeg 768w\" data-sizes=\"auto, (max-width: 537px) 100vw, 537px\" \/><\/p>\n<p>O primeiro an\u00fancio da mudan\u00e7a foi no final de 2021, entretanto, somente agora o Google formalizou essa altera\u00e7\u00e3o aos administradores pelos perfis no Google Maps.<\/p>\n<p>A expectativa \u00e9 que a partir do segundo semestre j\u00e1 n\u00e3o seja mais poss\u00edvel acessar o Google Meu Neg\u00f3cio. Para empresas que tem mais de uma unidade, uma solu\u00e7\u00e3o chamada <strong>Perfil do Google Business<\/strong> estar\u00e1 dispon\u00edvel.<\/p>\n<p>J\u00e1 para quem tem apenas uma listagem, basta digitar o nome dela no Google (como exemplificado na imagem da pr\u00f3pria Ag\u00eancia Explorer) e editar diretamente pela pesquisa do Google.<\/p>\n<p>Abra\u00e7os e at\u00e9 a pr\u00f3xima semana!<\/p>\n<p>Rog\u00e9rio Salgado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O m\u00eas de maio ainda n\u00e3o terminou, entretanto, j\u00e1 est\u00e1 marcado por diversas pequenas novidades e melhorias que o Google est\u00e1 aplicando em suas plataformas.<\/p>\n","protected":false},"author":2,"featured_media":572,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[9,8],"tags":[20,45,46,37,12],"class_list":["post-567","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-ads","category-artigo","tag-analytics","tag-google-ads","tag-google-meu-negocio","tag-novidades","tag-redes-sociais"],"fimg_url":"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2022\/05\/Design-sem-nome.png","_links":{"self":[{"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/posts\/567","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/comments?post=567"}],"version-history":[{"count":1,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/posts\/567\/revisions"}],"predecessor-version":[{"id":1746,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/posts\/567\/revisions\/1746"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/media\/572"}],"wp:attachment":[{"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/media?parent=567"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/categories?post=567"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/tags?post=567"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}