{"id":1385,"date":"2023-05-23T09:59:53","date_gmt":"2023-05-23T12:59:53","guid":{"rendered":"https:\/\/greenyellow-mandrill-630795.hostingersite.com\/blog\/?p=1385"},"modified":"2023-12-14T13:33:26","modified_gmt":"2023-12-14T16:33:26","slug":"instagram-desenvolve-aplicativo-de-texto-para-concorrer-com-o-twitter","status":"publish","type":"post","link":"https:\/\/agenciaexplorer.com.br\/blog\/artigo\/instagram-desenvolve-aplicativo-de-texto-para-concorrer-com-o-twitter\/","title":{"rendered":"Instagram desenvolve aplicativo de texto para concorrer com o Twitter"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">O Instagram est\u00e1 se preparando para lan\u00e7ar um novo aplicativo de texto nos Estados Unidos. Com um limite de 500 caracteres por postagem, a plataforma pretende competir diretamente com o Twitter.<\/p>\n\n\n\n<!--more-->\n\n\n\n<p class=\"wp-block-paragraph\">A informa\u00e7\u00e3o foi divulgada por Lia Haberman, professora de marketing social e influ\u00eancia na UCLA (Universidade da Calif\u00f3rnia em Los Angeles) e uma das selecionadas para testar o novo aplicativo da Meta.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De acordo com a ag\u00eancia de not\u00edcias Bloomberg, a Meta planeja lan\u00e7ar o aplicativo em junho deste ano. Imagens divulgadas por Haberman mostram algumas funcionalidades da plataforma de texto, que ser\u00e1 baseada no c\u00f3digo-fonte do Instagram. Al\u00e9m disso, contas verificadas no Instagram tamb\u00e9m ser\u00e3o verificadas no novo aplicativo, chamado Projeto 92.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A nova plataforma de texto da Meta permitir\u00e1 aos usu\u00e1rios interagir por meio de curtidas, respostas, republica\u00e7\u00f5es e mensagens privadas. Tamb\u00e9m ser\u00e1 poss\u00edvel compartilhar v\u00eddeos de at\u00e9 cinco minutos, fotos e links. Essas op\u00e7\u00f5es s\u00e3o semelhantes \u00e0s oferecidas pelo Twitter, que possui um limite de 280 caracteres para usu\u00e1rios da vers\u00e3o gratuita.<\/p>\n\n\n\n<figure class=\"wp-block-image size-large\"><img loading=\"lazy\" decoding=\"async\" width=\"1024\" height=\"568\" src=\"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/themes\/maktub\/assets\/images\/transparent.gif\" data-lazy=\"true\" data-src=\"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2023\/05\/Insta-Artigo-da-proxima-semana-1024x568.jpeg\" alt=\"\" class=\"wp-image-1386\" title=\"\" data-srcset=\"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2023\/05\/Insta-Artigo-da-proxima-semana-1024x568.jpeg 1024w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2023\/05\/Insta-Artigo-da-proxima-semana-300x167.jpeg 300w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2023\/05\/Insta-Artigo-da-proxima-semana-768x426.jpeg 768w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2023\/05\/Insta-Artigo-da-proxima-semana-1536x853.jpeg 1536w, https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2023\/05\/Insta-Artigo-da-proxima-semana-2048x1137.jpeg 2048w\" data-sizes=\"auto, (max-width: 1024px) 100vw, 1024px\" \/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A modera\u00e7\u00e3o de conte\u00fado da nova rede social de texto da Meta seguir\u00e1 as regras da comunidade do Instagram. Enquanto isso, o Twitter recentemente flexibilizou suas pol\u00edticas de remo\u00e7\u00e3o e rotulagem de postagens desde a aquisi\u00e7\u00e3o por Elon Musk, o que gerou opini\u00f5es divergentes entre os usu\u00e1rios.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">O aplicativo tamb\u00e9m oferecer\u00e1 autentica\u00e7\u00e3o de dois fatores gratuitamente, segundo relatos de Haberman. Isso contrasta com o Twitter, que restringe essa op\u00e7\u00e3o aos assinantes do Twitter Blue, uma assinatura mensal que custa a partir de R$ 42.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Assim como a nova rede social Bluesky, desenvolvida pelo cofundador do Twitter Jack Dorsey, a plataforma de texto da Meta ser\u00e1 descentralizada. Isso significa que os usu\u00e1rios poder\u00e3o interagir com contas e postagens de outras redes sociais abertas.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Com o lan\u00e7amento relativamente pr\u00f3ximo, a competi\u00e7\u00e3o entre as plataformas promete aquecer o mercado das redes sociais.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Abra\u00e7os,<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Rog\u00e9rio Salgado<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O Instagram est\u00e1 se preparando para lan\u00e7ar um novo aplicativo de texto nos Estados Unidos. Com um limite de 500 caracteres por postagem, a plataforma&#8230;<\/p>\n","protected":false},"author":2,"featured_media":1387,"comment_status":"closed","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"inline_featured_image":false,"footnotes":""},"categories":[8,15],"tags":[13,25,12,56],"class_list":["post-1385","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-artigo","category-socialmedia","tag-instagram","tag-meta","tag-redes-sociais","tag-twitter"],"fimg_url":"https:\/\/agenciaexplorer.com.br\/blog\/wp-content\/uploads\/2023\/05\/Insta-Capa-do-artigo-da-proxima-semana.jpg","_links":{"self":[{"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/posts\/1385","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/comments?post=1385"}],"version-history":[{"count":1,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/posts\/1385\/revisions"}],"predecessor-version":[{"id":1388,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/posts\/1385\/revisions\/1388"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/media\/1387"}],"wp:attachment":[{"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/media?parent=1385"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/categories?post=1385"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agenciaexplorer.com.br\/blog\/wp-json\/wp\/v2\/tags?post=1385"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}